{"id":41124,"date":"2025-09-30T10:21:00","date_gmt":"2025-09-30T08:21:00","guid":{"rendered":"https:\/\/nabenhauer-consulting.com\/blog\/?p=41124"},"modified":"2025-10-07T21:35:11","modified_gmt":"2025-10-07T19:35:11","slug":"virtuelle-verkaufsmethode","status":"publish","type":"post","link":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/","title":{"rendered":"Virtuelle Verkaufsmethode: So funktioniert Verkaufen ohne Vor-Ort-Termin"},"content":{"rendered":"\n<p>Seit 2020 sind pers\u00f6nliche Gespr\u00e4che vor Ort mit dem Kunden nicht mehr so einfach umzusetzen.<\/p>\n\n\n\n<p>Reisen werden zum Spie\u00dfrutenlauf.<\/p>\n\n\n\n<p>Terminplanungen treiben die Verk\u00e4ufer in den Wahnsinn.<\/p>\n\n\n\n<p>Und die Kosten, die die Verkaufsabteilung seit jeher verursacht, sind oft inakzeptabel.<\/p>\n\n\n\n<p>Nach diesem harten Krisenjahr hat sich die Welt drastisch ver\u00e4ndert und mit ihr auch die Art und Weise wie wir an unsere Kunden herantreten. Pers\u00f6nliche Meetings, Reisen, Kundengespr\u00e4che vor Ort &#8211; was fr\u00fcher selbstverst\u00e4ndlich war, wir nun immer mehr zu einer Herausforderung.&nbsp;<\/p>\n\n\n\n<p>Fakt ist: Das bekannte Verkaufssystem hat ausgedient, die Zeit f\u00fcr eine Verkaufsrevolution ist gekommen.<\/p>\n\n\n\n<p>Ein System, das eine digitale standardisierte und automatisierte Verkaufsl\u00f6sungen m\u00f6glich macht.<\/p>\n\n\n\n<p><strong>Jetzt Webinar anschauen!&nbsp;<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/nabenhauer-consulting.com\/webinar-virtuelle-verkaufsmethode\/\">\u25ba\u25ba\u25baBitte hier klicken<\/a><\/p>\n\n\n\n<p>Doch geht das denn \u00fcberhaupt?<\/p>\n\n\n\n<p>Was sollen denn Unternehmen machen, die auf ein Verkaufsgespr\u00e4ch vor Ort beim Kunden angewiesen sind?<\/p>\n\n\n\n<p>Bei denen der Kunde die Ware pers\u00f6nlich testen muss? Verkosten muss?<\/p>\n\n\n\n<p>F\u00fcr Unternehmen, die ein erkl\u00e4rungsbed\u00fcrftiges Produkt verkaufen und es dem Kunden pers\u00f6nlich erkl\u00e4ren m\u00fcssen?<\/p>\n\n\n\n<p>Und ein standardisierter Verkauf? Automatisieren?<\/p>\n\n\n\n<p>Nein, unm\u00f6glich! Der Verk\u00e4ufer muss jeden Kunden pers\u00f6nlich betreuen, um zu \u00fcberzeugen, um Probleme zu l\u00f6sen. Die Menschen vertrauen dem Verk\u00e4ufer als Person!<\/p>\n\n\n\n<p><strong>Nein, das kann man nicht digitalisieren.<\/strong><\/p>\n\n\n\n<p>Wissen Sie was? Ich stimme Ihnen sogar zu. Die Person des Verk\u00e4ufers ist wichtig. Das Testen und Verkosten der Produkte vor Ort ist wichtig. Das Erkl\u00e4ren und Vorf\u00fchren ist wichtig. Die pers\u00f6nliche Pr\u00e4senz ist es aber nicht! Und ja, man kann es digitalisieren und automatisieren.<\/p>\n\n\n\n<p>Sie glauben mir nicht?<\/p>\n\n\n\n<p>Dann lade ich Sie hiermit zu meinem neuen kostenfreien Webinar \u201cVirtuelle Verkaufsmethode &#8211; Trotz Einschr\u00e4nkungen vor Ort verkaufen. Produktiver. Kosteng\u00fcnstiger. Stressfreier.\u201d ein.<\/p>\n\n\n\n<p>Hier werden Sie Antworten auf Ihre Frage finden. Darin werde ich Ihnen zeigen, dass Sie auch virtuell ein Verkaufsgespr\u00e4ch f\u00fchren k\u00f6nnen, bei dem der Kunde nichts vom Verkaufserlebnis einb\u00fc\u00dfen muss.<\/p>\n\n\n\n<p>Vollgepackt mit wertvollen Infos und Tipps werden Sie in diesem 60-Minuten-Webinar folgendes lernen:<\/p>\n\n\n\n<p>Welche Auswirkungen Auflagen, Verbote und Beschr\u00e4nkungen auf den Verkauf haben<br \/>Wie die hohe Kosten der Verkaufsabteilung und der Terminwahnsinn der Verk\u00e4ufer einem Unternehmen schaden<br \/>Welche Fallstricke und M\u00e4ngel die gebr\u00e4uchliche Verkaufsstrategie in sich tr\u00e4gt und wie sie gegen das Potenzial Ihres Verk\u00e4ufers arbeitet<br \/>Wie Sie mit einem neuen virtuellen Verkaufssystem auch vor Ort verkaufen k\u00f6nnen, ohne vor Ort sein zu m\u00fcssen<br \/>Wie Sie damit hei\u00dfe Leads herausfiltern k\u00f6nnen, damit sich Ihre Verk\u00e4ufer ganz auf diese Qualit\u00e4tskunden konzentrieren k\u00f6nnen<br \/>Wie Sie Ihren Verkauf trotz Beschr\u00e4nkungen und Auflagen problemlos und stressfrei weiterf\u00fchren k\u00f6nnen<br \/>Wie Sie damit das volle Potenzial Ihrer Verk\u00e4ufer ausnutzen k\u00f6nnen &#8211; speziell in Krisenzeiten<br \/>Wie Sie mit dem virtuellen System Ihren Verkaufsprozess qualitativ immer auf 100% halten<br \/>Wie Sie Ressourcen und Kosten besser \u00fcberblicken und einfacher vorausplanen k\u00f6nnen<br \/>Wie Sie Ihren Verkauf produktiver gestalten, Ihren administrativen Aufwand reduzieren und Ihre Kosten senken k\u00f6nnen<br \/>Wie Sie Ihr Verkaufssystem digitalisieren und automatisieren k\u00f6nnen, ohne Einbu\u00dfen des Verkaufserlebnisses&nbsp; f\u00fcr den Kunden<br \/>Und wie Sie die Arbeitszeit Ihres Verk\u00e4ufers optimieren und stressfreier gestalten k\u00f6nnen&nbsp;<\/p>\n\n\n\n<p>Ich verspreche, dass dieses Webinar Ihnen eine ganz neue Perspektive auf den Verkauf zeigen wird. Sie werden am Ende eine neue Verkaufsl\u00f6sung kennen, die auch in Zeiten des Social Distancing Ihren Verkauf auf ein neues Level heben wird.<\/p>\n\n\n\n<p><strong>Es ist kostenfrei und Sie k\u00f6nnen gleich damit starten &#8211; keine Wartezeit.<\/strong><\/p>\n\n\n\n<p>Jetzt Webinar anschauen!<\/p>\n\n\n\n<p><a href=\"https:\/\/nabenhauer-consulting.com\/webinar-virtuelle-verkaufsmethode\/\">&nbsp;\u25ba\u25ba\u25baBitte hier klicken<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die virtuelle Verkaufsmethode ersetzt klassische Vor-Ort-Termine durch digitale L\u00f6sungen. Im kostenfreien Webinar lernen Unternehmen, wie sie auch ohne pers\u00f6nliche Kundengespr\u00e4che erfolgreich verkaufen k\u00f6nnen \u2013 effizient, kosteng\u00fcnstig und stressfrei.<\/p>\n","protected":false},"author":9,"featured_media":41125,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_edit_lock":["1759866555:9"],"_wp_old_date":["2025-10-07"],"_thumbnail_id":["41125"],"_format_link_url":[""],"_format_quote_source_url":[""],"_format_quote_source_name":[""],"_format_audio_embed":[""],"_format_video_embed":[""],"_edit_last":["9"],"penci_post_views_count":["479"],"penci_post_week_views_count":["6"],"penci_post_month_views_count":["17"],"_b2s_post_meta":["a:7:{s:8:\"og_title\";s:72:\"Virtuelle Verkaufsmethode: So funktioniert Verkaufen ohne Vor-Ort-Termin\";s:7:\"og_desc\";s:258:\"Die virtuelle Verkaufsmethode ersetzt klassische Vor-Ort-Termine durch digitale L\u00f6sungen. Im kostenfreien Webinar lernen Unternehmen, wie sie auch ohne pers\u00f6nliche Kundengespr\u00e4che erfolgreich verkaufen k\u00f6nnen \u2013 effizient, kosteng\u00fcnstig und stressfrei.\";s:8:\"og_image\";s:95:\"https:\/\/nabenhauer-consulting.com\/blog\/wp-content\/uploads\/2025\/10\/Virtuelle-Verkaufsmethode.jpg\";s:12:\"og_image_alt\";s:0:\"\";s:10:\"card_title\";s:72:\"Virtuelle Verkaufsmethode: So funktioniert Verkaufen ohne Vor-Ort-Termin\";s:9:\"card_desc\";s:258:\"Die virtuelle Verkaufsmethode ersetzt klassische Vor-Ort-Termine durch digitale L\u00f6sungen. Im kostenfreien Webinar lernen Unternehmen, wie sie auch ohne pers\u00f6nliche Kundengespr\u00e4che erfolgreich verkaufen k\u00f6nnen \u2013 effizient, kosteng\u00fcnstig und stressfrei.\";s:10:\"card_image\";s:95:\"https:\/\/nabenhauer-consulting.com\/blog\/wp-content\/uploads\/2025\/10\/Virtuelle-Verkaufsmethode.jpg\";}"],"_zerobounce_force_enable":["0"],"_zerobounce_individual_disable":["0"],"_zerobounce_specific_url":[""],"_format_gallery_images":["a:0:{}"],"penci_custom_sidebar_page_display":[""],"_oembed_92e0f51be67c1e4f707ae09dcae0f7f2":["<iframe title=\"Der SocialMedia-Club von Robert Nabenhauer (PreSales Marketing)\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/QUmpVtSBgTg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"penci_custom_sidebar_left_page_field":[""],"penci_post_sidebar_display":[""],"penci_single_style":[""],"_oembed_time_92e0f51be67c1e4f707ae09dcae0f7f2":["1759865711"],"penci_pfeatured_image_ratio":[""],"penci_enable_jarallax_single":[""],"penci_post_hide_featuimg":[""],"_yoast_wpseo_primary_category":["1668"],"_yoast_wpseo_linkdex":["71"],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":["4"],"_yoast_wpseo_wordproof_timestamp":[""]},"categories":[1684,1184,1668,1649,1775],"tags":[1765,1764,1771,1767,51,1773,1766,1774,1770,1768,1769,1772,1763],"class_list":["post-41124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digitale-weiterbildung","category-digitalisierung","category-online-marketing","category-online-werbung","category-verkauf-digitalisierung","tag-automatisierter-verkauf","tag-digitales-verkaufssystem","tag-kostenfreies-webinar","tag-krisenmanagement","tag-nabenhauer-consulting","tag-online-verkauf","tag-social-distancing","tag-verkauf-ohne-reisekosten","tag-verkaufsoptimierung","tag-verkaufsstrategie","tag-vertrieb-2025","tag-vertrieb-digitalisieren","tag-virtuelle-verkaufsmethode"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Virtuelle Verkaufsmethode<\/title>\n<meta name=\"description\" content=\"Virtuelle Verkaufsmethode: So verkaufen Sie trotz Einschr\u00e4nkungen effizient und digital \u2013 jetzt kostenfreies Webinar ansehen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Nabenhauer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/\"},\"author\":{\"name\":\"Robert Nabenhauer\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/#\\\/schema\\\/person\\\/096a2ccb360b609fe9151179d06ad08d\"},\"headline\":\"Virtuelle Verkaufsmethode: So funktioniert Verkaufen ohne Vor-Ort-Termin\",\"datePublished\":\"2025-09-30T08:21:00+00:00\",\"dateModified\":\"2025-10-07T19:35:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/\"},\"wordCount\":593,\"image\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Virtuelle-Verkaufsmethode.jpg\",\"keywords\":[\"automatisierter Verkauf\",\"digitales Verkaufssystem\",\"kostenfreies Webinar\",\"Krisenmanagement\",\"Nabenhauer Consulting\",\"Online-Verkauf\",\"Social Distancing\",\"Verkauf ohne Reisekosten\",\"Verkaufsoptimierung\",\"Verkaufsstrategie\",\"Vertrieb 2025\",\"Vertrieb digitalisieren\",\"virtuelle Verkaufsmethode\"],\"articleSection\":[\"Digitale Weiterbildung\",\"digitalisierung\",\"Online-Marketing\",\"Online-Werbung\",\"Verkauf &amp; Digitalisierung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/\",\"url\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/\",\"name\":\"Virtuelle Verkaufsmethode\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Virtuelle-Verkaufsmethode.jpg\",\"datePublished\":\"2025-09-30T08:21:00+00:00\",\"dateModified\":\"2025-10-07T19:35:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/#\\\/schema\\\/person\\\/096a2ccb360b609fe9151179d06ad08d\"},\"description\":\"Virtuelle Verkaufsmethode: So verkaufen Sie trotz Einschr\u00e4nkungen effizient und digital \u2013 jetzt kostenfreies Webinar ansehen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Virtuelle-Verkaufsmethode.jpg\",\"contentUrl\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Virtuelle-Verkaufsmethode.jpg\",\"width\":1280,\"height\":889,\"caption\":\"Virtuelle Verkaufsmethode f\u00fcr effizienten Vertrieb ohne Vor-Ort-Termine \u2013 das Webinar zeigt die L\u00f6sung f\u00fcr moderne Verkaufsteams.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/virtuelle-verkaufsmethode\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Virtuelle Verkaufsmethode: So funktioniert Verkaufen ohne Vor-Ort-Termin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/\",\"name\":\"PreSales Marketing\",\"description\":\"Das Erfolgsprinzip\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/#\\\/schema\\\/person\\\/096a2ccb360b609fe9151179d06ad08d\",\"name\":\"Robert Nabenhauer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26c243c3cac63ea68e5cf24a95ae004fc90a57a5131e82816269770cc6898838?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26c243c3cac63ea68e5cf24a95ae004fc90a57a5131e82816269770cc6898838?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26c243c3cac63ea68e5cf24a95ae004fc90a57a5131e82816269770cc6898838?s=96&d=mm&r=g\",\"caption\":\"Robert Nabenhauer\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Virtuelle Verkaufsmethode","description":"Virtuelle Verkaufsmethode: So verkaufen Sie trotz Einschr\u00e4nkungen effizient und digital \u2013 jetzt kostenfreies Webinar ansehen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/","twitter_misc":{"Verfasst von":"Robert Nabenhauer","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/#article","isPartOf":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/"},"author":{"name":"Robert Nabenhauer","@id":"https:\/\/nabenhauer-consulting.com\/blog\/#\/schema\/person\/096a2ccb360b609fe9151179d06ad08d"},"headline":"Virtuelle Verkaufsmethode: So funktioniert Verkaufen ohne Vor-Ort-Termin","datePublished":"2025-09-30T08:21:00+00:00","dateModified":"2025-10-07T19:35:11+00:00","mainEntityOfPage":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/"},"wordCount":593,"image":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/#primaryimage"},"thumbnailUrl":"https:\/\/nabenhauer-consulting.com\/blog\/wp-content\/uploads\/2025\/10\/Virtuelle-Verkaufsmethode.jpg","keywords":["automatisierter Verkauf","digitales Verkaufssystem","kostenfreies Webinar","Krisenmanagement","Nabenhauer Consulting","Online-Verkauf","Social Distancing","Verkauf ohne Reisekosten","Verkaufsoptimierung","Verkaufsstrategie","Vertrieb 2025","Vertrieb digitalisieren","virtuelle Verkaufsmethode"],"articleSection":["Digitale Weiterbildung","digitalisierung","Online-Marketing","Online-Werbung","Verkauf &amp; Digitalisierung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/","url":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/","name":"Virtuelle Verkaufsmethode","isPartOf":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/#primaryimage"},"image":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/#primaryimage"},"thumbnailUrl":"https:\/\/nabenhauer-consulting.com\/blog\/wp-content\/uploads\/2025\/10\/Virtuelle-Verkaufsmethode.jpg","datePublished":"2025-09-30T08:21:00+00:00","dateModified":"2025-10-07T19:35:11+00:00","author":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/#\/schema\/person\/096a2ccb360b609fe9151179d06ad08d"},"description":"Virtuelle Verkaufsmethode: So verkaufen Sie trotz Einschr\u00e4nkungen effizient und digital \u2013 jetzt kostenfreies Webinar ansehen!","breadcrumb":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/#primaryimage","url":"https:\/\/nabenhauer-consulting.com\/blog\/wp-content\/uploads\/2025\/10\/Virtuelle-Verkaufsmethode.jpg","contentUrl":"https:\/\/nabenhauer-consulting.com\/blog\/wp-content\/uploads\/2025\/10\/Virtuelle-Verkaufsmethode.jpg","width":1280,"height":889,"caption":"Virtuelle Verkaufsmethode f\u00fcr effizienten Vertrieb ohne Vor-Ort-Termine \u2013 das Webinar zeigt die L\u00f6sung f\u00fcr moderne Verkaufsteams."},{"@type":"BreadcrumbList","@id":"https:\/\/nabenhauer-consulting.com\/blog\/virtuelle-verkaufsmethode\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nabenhauer-consulting.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Virtuelle Verkaufsmethode: So funktioniert Verkaufen ohne Vor-Ort-Termin"}]},{"@type":"WebSite","@id":"https:\/\/nabenhauer-consulting.com\/blog\/#website","url":"https:\/\/nabenhauer-consulting.com\/blog\/","name":"PreSales Marketing","description":"Das Erfolgsprinzip","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nabenhauer-consulting.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/nabenhauer-consulting.com\/blog\/#\/schema\/person\/096a2ccb360b609fe9151179d06ad08d","name":"Robert Nabenhauer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/26c243c3cac63ea68e5cf24a95ae004fc90a57a5131e82816269770cc6898838?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/26c243c3cac63ea68e5cf24a95ae004fc90a57a5131e82816269770cc6898838?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/26c243c3cac63ea68e5cf24a95ae004fc90a57a5131e82816269770cc6898838?s=96&d=mm&r=g","caption":"Robert Nabenhauer"}}]}},"_links":{"self":[{"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/posts\/41124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/comments?post=41124"}],"version-history":[{"count":1,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/posts\/41124\/revisions"}],"predecessor-version":[{"id":41126,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/posts\/41124\/revisions\/41126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/media\/41125"}],"wp:attachment":[{"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/media?parent=41124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/categories?post=41124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/tags?post=41124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}