{"id":11772,"date":"2016-02-05T14:03:47","date_gmt":"2016-02-05T13:03:47","guid":{"rendered":"http:\/\/www.presalesmarketing-blog.com\/?p=11772"},"modified":"2016-02-05T14:03:47","modified_gmt":"2016-02-05T13:03:47","slug":"display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent","status":"publish","type":"post","link":"https:\/\/nabenhauer-consulting.com\/blog\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/","title":{"rendered":"DISPLAY ADVERTISING &#8211; Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf 58 Prozent"},"content":{"rendered":"<div class=\"snippet\"><strong><strong> DISPLAY ADVERTISING &#8211; Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf<br \/>\n58 Prozent<\/strong><\/strong>&nbsp;<\/p>\n<p>Die Sichtbarkeitsraten f\u00fcr Display Ads befinden sich im deutschen Markt weiter im Sinkflug: Unsere aktuellen \u201eViewability Benchmarks\u201c belegen einen anhaltenden Abw\u00e4rtstrend bei der Sichtbarkeit von Display-Werbung im europ\u00e4ischen Markt. Mit einem erneuten R\u00fcckgang der Viewability&#8230;<br \/>\n<a href=\"https:\/\/127.0.0.1:8000\/2016\/02\/deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/\" target=\"_blank\" rel=\"nofollow\">Original Artikel ansehen<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>DISPLAY ADVERTISING &#8211; Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf 58 Prozent&nbsp; Die Sichtbarkeitsraten f\u00fcr Display&hellip;<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"title":[" DISPLAY ADVERTISING - Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf \r\n58 Prozent\r\n\r\n"],"description":[" DISPLAY ADVERTISING - Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf \r\n58 Prozent\r\n\r\nDie Sichtbarkeitsraten f\u00fcr Display Ads be"],"keywords":[""],"_edit_lock":["1454677329:9"],"_edit_last":["9"],"feature_post":[null],"post_media_type":["image"],"quote_author":[""],"link":[""],"embed_code":[""],"slider_button":["0"],"slider_effect":["fade"],"slide_speed":[""],"image_array":[""],"sidebar_selector":[null],"_av_alb_posts_elements_state":["a:0:{}"],"_av_el_mgr_version":["1.0"],"_av_alb_element_mgr_version":["1.0.1"],"penci_post_views_count":["803"],"penci_post_week_views_count":["4"],"penci_post_month_views_count":["5"],"_oembed_92e0f51be67c1e4f707ae09dcae0f7f2":["<iframe title=\"Der SocialMedia-Club von Robert Nabenhauer (PreSales Marketing)\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/QUmpVtSBgTg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>"],"_oembed_time_92e0f51be67c1e4f707ae09dcae0f7f2":["1572444089"]},"categories":[315],"tags":[],"class_list":["post-11772","post","type-post","status-publish","format-standard","hentry","category-online-marketing-magazin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u25b7DISPLAY ADVERTISING - Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf 58 Prozent - PreSales Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nabenhauer-consulting.com\/blog\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Nabenhauer\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\\\/\"},\"author\":{\"name\":\"Robert Nabenhauer\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/#\\\/schema\\\/person\\\/d74c98cb4163d1bbdc859d185c6c1812\"},\"headline\":\"DISPLAY ADVERTISING &#8211; Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf 58 Prozent\",\"datePublished\":\"2016-02-05T13:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\\\/\"},\"wordCount\":67,\"commentCount\":0,\"articleSection\":[\"Online Marketing Magazin\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\\\/\",\"url\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\\\/\",\"name\":\"\u25b7DISPLAY ADVERTISING - Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf 58 Prozent - PreSales Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/#website\"},\"datePublished\":\"2016-02-05T13:03:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/#\\\/schema\\\/person\\\/d74c98cb4163d1bbdc859d185c6c1812\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DISPLAY ADVERTISING &#8211; Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf 58 Prozent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/\",\"name\":\"PreSales Marketing\",\"description\":\"Das Erfolgsprinzip\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nabenhauer-consulting.com\\\/blog\\\/#\\\/schema\\\/person\\\/d74c98cb4163d1bbdc859d185c6c1812\",\"name\":\"Robert Nabenhauer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e55a96e72516231a0063daccde5496b98f44c8509034a9595f7458b622ca191c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e55a96e72516231a0063daccde5496b98f44c8509034a9595f7458b622ca191c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e55a96e72516231a0063daccde5496b98f44c8509034a9595f7458b622ca191c?s=96&d=mm&r=g\",\"caption\":\"Robert Nabenhauer\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7DISPLAY ADVERTISING - Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf 58 Prozent - PreSales Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nabenhauer-consulting.com\/blog\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/","twitter_misc":{"Verfasst von":"Robert Nabenhauer"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nabenhauer-consulting.com\/blog\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/#article","isPartOf":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/"},"author":{"name":"Robert Nabenhauer","@id":"https:\/\/nabenhauer-consulting.com\/blog\/#\/schema\/person\/d74c98cb4163d1bbdc859d185c6c1812"},"headline":"DISPLAY ADVERTISING &#8211; Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf 58 Prozent","datePublished":"2016-02-05T13:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/"},"wordCount":67,"commentCount":0,"articleSection":["Online Marketing Magazin"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/nabenhauer-consulting.com\/blog\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/","url":"https:\/\/nabenhauer-consulting.com\/blog\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/","name":"\u25b7DISPLAY ADVERTISING - Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf 58 Prozent - PreSales Marketing","isPartOf":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/#website"},"datePublished":"2016-02-05T13:03:47+00:00","author":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/#\/schema\/person\/d74c98cb4163d1bbdc859d185c6c1812"},"breadcrumb":{"@id":"https:\/\/nabenhauer-consulting.com\/blog\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nabenhauer-consulting.com\/blog\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nabenhauer-consulting.com\/blog\/display-advertising-deutsche-sichtbarkeitsraten-fuer-display-ads-fallen-auf-58-prozent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nabenhauer-consulting.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DISPLAY ADVERTISING &#8211; Deutsche Sichtbarkeitsraten f\u00fcr Display Ads fallen auf 58 Prozent"}]},{"@type":"WebSite","@id":"https:\/\/nabenhauer-consulting.com\/blog\/#website","url":"https:\/\/nabenhauer-consulting.com\/blog\/","name":"PreSales Marketing","description":"Das Erfolgsprinzip","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nabenhauer-consulting.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/nabenhauer-consulting.com\/blog\/#\/schema\/person\/d74c98cb4163d1bbdc859d185c6c1812","name":"Robert Nabenhauer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e55a96e72516231a0063daccde5496b98f44c8509034a9595f7458b622ca191c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e55a96e72516231a0063daccde5496b98f44c8509034a9595f7458b622ca191c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e55a96e72516231a0063daccde5496b98f44c8509034a9595f7458b622ca191c?s=96&d=mm&r=g","caption":"Robert Nabenhauer"}}]}},"_links":{"self":[{"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/posts\/11772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/comments?post=11772"}],"version-history":[{"count":0,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/posts\/11772\/revisions"}],"wp:attachment":[{"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/media?parent=11772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/categories?post=11772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nabenhauer-consulting.com\/blog\/wp-json\/wp\/v2\/tags?post=11772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}